{"id":2221455,"date":"2026-05-06T09:54:57","date_gmt":"2026-05-06T07:54:57","guid":{"rendered":"https:\/\/luretta.com\/?post_type=product&#038;p=2221455"},"modified":"2026-06-18T10:39:46","modified_gmt":"2026-06-18T08:39:46","slug":"thara-2025-bottiglia750ml","status":"publish","type":"product","link":"https:\/\/luretta.com\/en\/shop\/thara-2025-bottiglia750ml\/","title":{"rendered":"Thara 2025 &#8211; Bottiglia(750ml.)"},"content":{"rendered":"<p>Un vino che fa della giovent\u00f9 il suo punto di forza: fresco, agile e immediato, il nostro Thara combina i profumi della Malvasia Aromatica di Candia alla mineralit\u00e0 dello Chardonnay. Da stappare durante le calde serate estive, ideale per un aperitivo all\u2019aria aperta o una cena con vista mare a base di pesce.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un vino che fa della giovent\u00f9 il suo punto di forza: fresco, agile e immediato, il nostro Thara combina i profumi della Malvasia Aromatica di Candia alla mineralit\u00e0 dello Chardonnay. Da stappare durante le calde serate estive, ideale per un aperitivo all\u2019aria aperta o una cena con vista mare a base di pesce.<\/p>\n","protected":false},"featured_media":2221642,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[227],"product_cat":[229,195,136],"product_tag":[],"vitigni":[173,176],"produttori":[],"formato":[143],"classe_sconto":[222],"class_list":["post-2221455","product","type-product","status-publish","has-post-thumbnail","product_brand-scontabile","product_cat-thara","product_cat-vini","product_cat-vini-bianchi","vitigni-chardonnay","vitigni-malvasia-aromatica-di-candia","formato-bottiglia750ml","classe_sconto-sconto-club","member-discount","discount-restricted","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Thara 2025 - Bottiglia(750ml.) - Cantina Luretta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/luretta.com\/shop\/thara-2025-bottiglia750ml\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Thara 2025 - Bottiglia(750ml.) - Cantina Luretta\" \/>\n<meta property=\"og:description\" content=\"Un vino che fa della giovent\u00f9 il suo punto di forza: fresco, agile e immediato, il nostro Thara combina i profumi della Malvasia Aromatica di Candia alla mineralit\u00e0 dello Chardonnay. Da stappare durante le calde serate estive, ideale per un aperitivo all\u2019aria aperta o una cena con vista mare a base di pesce.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/luretta.com\/shop\/thara-2025-bottiglia750ml\/\" \/>\n<meta property=\"og:site_name\" content=\"Cantina Luretta\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-18T08:39:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/luretta.com\/wp-content\/uploads\/2026\/05\/luretta_bottles_1000x1200px_150dpi_Thara.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/luretta.com\\\/shop\\\/thara-2025-bottiglia750ml\\\/\",\"url\":\"https:\\\/\\\/luretta.com\\\/shop\\\/thara-2025-bottiglia750ml\\\/\",\"name\":\"Thara 2025 - Bottiglia(750ml.) - Cantina Luretta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/luretta.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/luretta.com\\\/shop\\\/thara-2025-bottiglia750ml\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/luretta.com\\\/shop\\\/thara-2025-bottiglia750ml\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/luretta.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/luretta_bottles_1000x1200px_150dpi_Thara.png\",\"datePublished\":\"2026-05-06T07:54:57+00:00\",\"dateModified\":\"2026-06-18T08:39:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/luretta.com\\\/shop\\\/thara-2025-bottiglia750ml\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/luretta.com\\\/shop\\\/thara-2025-bottiglia750ml\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/luretta.com\\\/shop\\\/thara-2025-bottiglia750ml\\\/#primaryimage\",\"url\":\"https:\\\/\\\/luretta.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/luretta_bottles_1000x1200px_150dpi_Thara.png\",\"contentUrl\":\"https:\\\/\\\/luretta.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/luretta_bottles_1000x1200px_150dpi_Thara.png\",\"width\":1000,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/luretta.com\\\/shop\\\/thara-2025-bottiglia750ml\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/luretta.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Thara 2025 &#8211; Bottiglia(750ml.)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/luretta.com\\\/#website\",\"url\":\"https:\\\/\\\/luretta.com\\\/\",\"name\":\"Cantina Luretta\",\"description\":\"Vini dei colli piacentini\",\"publisher\":{\"@id\":\"https:\\\/\\\/luretta.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/luretta.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/luretta.com\\\/#organization\",\"name\":\"Cantina Luretta\",\"url\":\"https:\\\/\\\/luretta.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/luretta.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/luretta.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Logo-Luretta-bianco-1.png\",\"contentUrl\":\"https:\\\/\\\/luretta.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Logo-Luretta-bianco-1.png\",\"width\":492,\"height\":400,\"caption\":\"Cantina Luretta\"},\"image\":{\"@id\":\"https:\\\/\\\/luretta.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Thara 2025 - Bottiglia(750ml.) - Cantina Luretta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/luretta.com\/shop\/thara-2025-bottiglia750ml\/","og_locale":"en_US","og_type":"article","og_title":"Thara 2025 - Bottiglia(750ml.) - Cantina Luretta","og_description":"Un vino che fa della giovent\u00f9 il suo punto di forza: fresco, agile e immediato, il nostro Thara combina i profumi della Malvasia Aromatica di Candia alla mineralit\u00e0 dello Chardonnay. Da stappare durante le calde serate estive, ideale per un aperitivo all\u2019aria aperta o una cena con vista mare a base di pesce.","og_url":"https:\/\/luretta.com\/shop\/thara-2025-bottiglia750ml\/","og_site_name":"Cantina Luretta","article_modified_time":"2026-06-18T08:39:46+00:00","og_image":[{"width":1000,"height":1200,"url":"https:\/\/luretta.com\/wp-content\/uploads\/2026\/05\/luretta_bottles_1000x1200px_150dpi_Thara.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/luretta.com\/shop\/thara-2025-bottiglia750ml\/","url":"https:\/\/luretta.com\/shop\/thara-2025-bottiglia750ml\/","name":"Thara 2025 - Bottiglia(750ml.) - Cantina Luretta","isPartOf":{"@id":"https:\/\/luretta.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/luretta.com\/shop\/thara-2025-bottiglia750ml\/#primaryimage"},"image":{"@id":"https:\/\/luretta.com\/shop\/thara-2025-bottiglia750ml\/#primaryimage"},"thumbnailUrl":"https:\/\/luretta.com\/wp-content\/uploads\/2026\/05\/luretta_bottles_1000x1200px_150dpi_Thara.png","datePublished":"2026-05-06T07:54:57+00:00","dateModified":"2026-06-18T08:39:46+00:00","breadcrumb":{"@id":"https:\/\/luretta.com\/shop\/thara-2025-bottiglia750ml\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/luretta.com\/shop\/thara-2025-bottiglia750ml\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/luretta.com\/shop\/thara-2025-bottiglia750ml\/#primaryimage","url":"https:\/\/luretta.com\/wp-content\/uploads\/2026\/05\/luretta_bottles_1000x1200px_150dpi_Thara.png","contentUrl":"https:\/\/luretta.com\/wp-content\/uploads\/2026\/05\/luretta_bottles_1000x1200px_150dpi_Thara.png","width":1000,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/luretta.com\/shop\/thara-2025-bottiglia750ml\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Shop","item":"https:\/\/luretta.com\/shop\/"},{"@type":"ListItem","position":2,"name":"Thara 2025 &#8211; Bottiglia(750ml.)"}]},{"@type":"WebSite","@id":"https:\/\/luretta.com\/#website","url":"https:\/\/luretta.com\/","name":"Cantina Luretta","description":"Vini dei colli piacentini","publisher":{"@id":"https:\/\/luretta.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/luretta.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/luretta.com\/#organization","name":"Cantina Luretta","url":"https:\/\/luretta.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/luretta.com\/#\/schema\/logo\/image\/","url":"https:\/\/luretta.com\/wp-content\/uploads\/2023\/08\/Logo-Luretta-bianco-1.png","contentUrl":"https:\/\/luretta.com\/wp-content\/uploads\/2023\/08\/Logo-Luretta-bianco-1.png","width":492,"height":400,"caption":"Cantina Luretta"},"image":{"@id":"https:\/\/luretta.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/luretta.com\/en\/wp-json\/wp\/v2\/product\/2221455","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/luretta.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/luretta.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/luretta.com\/en\/wp-json\/wp\/v2\/comments?post=2221455"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/luretta.com\/en\/wp-json\/wp\/v2\/media\/2221642"}],"wp:attachment":[{"href":"https:\/\/luretta.com\/en\/wp-json\/wp\/v2\/media?parent=2221455"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/luretta.com\/en\/wp-json\/wp\/v2\/product_brand?post=2221455"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/luretta.com\/en\/wp-json\/wp\/v2\/product_cat?post=2221455"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/luretta.com\/en\/wp-json\/wp\/v2\/product_tag?post=2221455"},{"taxonomy":"vitigni","embeddable":true,"href":"https:\/\/luretta.com\/en\/wp-json\/wp\/v2\/vitigni?post=2221455"},{"taxonomy":"produttori","embeddable":true,"href":"https:\/\/luretta.com\/en\/wp-json\/wp\/v2\/produttori?post=2221455"},{"taxonomy":"formato","embeddable":true,"href":"https:\/\/luretta.com\/en\/wp-json\/wp\/v2\/formato?post=2221455"},{"taxonomy":"classe_sconto","embeddable":true,"href":"https:\/\/luretta.com\/en\/wp-json\/wp\/v2\/classe_sconto?post=2221455"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}